{"id":2878,"count":1,"description":"","link":"https:\/\/ptoshaft.supplies\/bs\/tag\/john-deere-snowblower-gearbox-manufacturer\/","name":"john deere snowblower gearbox manufacturer","slug":"john-deere-snowblower-gearbox-manufacturer","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ptoshaft.supplies\/bs\/wp-json\/wp\/v2\/tags\/2878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptoshaft.supplies\/bs\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ptoshaft.supplies\/bs\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ptoshaft.supplies\/bs\/wp-json\/wp\/v2\/posts?tags=2878"}],"curies":[{"name":"radni list","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}