{"id":4478,"count":1,"description":"","link":"https:\/\/ptoshaft.supplies\/bs\/tag\/cylinder-lpg-cylinder\/","name":"cylinder lpg cylinder","slug":"cylinder-lpg-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ptoshaft.supplies\/bs\/wp-json\/wp\/v2\/tags\/4478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptoshaft.supplies\/bs\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ptoshaft.supplies\/bs\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ptoshaft.supplies\/bs\/wp-json\/wp\/v2\/posts?tags=4478"}],"curies":[{"name":"radni list","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}