{"id":4066,"count":1,"description":"","link":"https:\/\/ptoshaft.supplies\/ceb\/tag\/pto-shaft-post-hole-digger\/","name":"pto shaft post hole digger","slug":"pto-shaft-post-hole-digger","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ptoshaft.supplies\/ceb\/wp-json\/wp\/v2\/tags\/4066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptoshaft.supplies\/ceb\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ptoshaft.supplies\/ceb\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ptoshaft.supplies\/ceb\/wp-json\/wp\/v2\/posts?tags=4066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}