{"id":4067,"count":1,"description":"","link":"https:\/\/ptoshaft.supplies\/de\/tag\/post-hole-digger-pto-shaft\/","name":"post hole digger pto shaft","slug":"post-hole-digger-pto-shaft","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ptoshaft.supplies\/de\/wp-json\/wp\/v2\/tags\/4067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptoshaft.supplies\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ptoshaft.supplies\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ptoshaft.supplies\/de\/wp-json\/wp\/v2\/posts?tags=4067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}