{"id":3869,"count":1,"description":"","link":"https:\/\/ptoshaft.supplies\/es\/tag\/pto-driveline-slip-clutch\/","name":"pto driveline slip clutch","slug":"pto-driveline-slip-clutch","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ptoshaft.supplies\/es\/wp-json\/wp\/v2\/tags\/3869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptoshaft.supplies\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ptoshaft.supplies\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ptoshaft.supplies\/es\/wp-json\/wp\/v2\/posts?tags=3869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}