{"id":4354,"count":1,"description":"","link":"https:\/\/ptoshaft.supplies\/es\/tag\/machine-laser\/","name":"machine laser","slug":"machine-laser","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ptoshaft.supplies\/es\/wp-json\/wp\/v2\/tags\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptoshaft.supplies\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ptoshaft.supplies\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ptoshaft.supplies\/es\/wp-json\/wp\/v2\/posts?tags=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}