{"id":4440,"count":2,"description":"","link":"https:\/\/ptoshaft.supplies\/es\/tag\/lathe-machine\/","name":"lathe machine","slug":"lathe-machine","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ptoshaft.supplies\/es\/wp-json\/wp\/v2\/tags\/4440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptoshaft.supplies\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ptoshaft.supplies\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ptoshaft.supplies\/es\/wp-json\/wp\/v2\/posts?tags=4440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}