{"id":4454,"count":1,"description":"","link":"https:\/\/ptoshaft.supplies\/es\/tag\/series-gear-reducer\/","name":"series gear reducer","slug":"series-gear-reducer","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ptoshaft.supplies\/es\/wp-json\/wp\/v2\/tags\/4454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptoshaft.supplies\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ptoshaft.supplies\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ptoshaft.supplies\/es\/wp-json\/wp\/v2\/posts?tags=4454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}