{"id":884,"count":1,"description":"","link":"https:\/\/ptoshaft.supplies\/es\/tag\/generator-pto-driven\/","name":"generator pto driven","slug":"generator-pto-driven","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ptoshaft.supplies\/es\/wp-json\/wp\/v2\/tags\/884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptoshaft.supplies\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ptoshaft.supplies\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ptoshaft.supplies\/es\/wp-json\/wp\/v2\/posts?tags=884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}