{"id":1885,"count":1,"description":"","link":"https:\/\/ptoshaft.supplies\/et\/tag\/mat-top-conveyors-china\/","name":"Mat Top Conveyors China","slug":"mat-top-conveyors-china","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ptoshaft.supplies\/et\/wp-json\/wp\/v2\/tags\/1885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptoshaft.supplies\/et\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ptoshaft.supplies\/et\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ptoshaft.supplies\/et\/wp-json\/wp\/v2\/posts?tags=1885"}],"curies":[{"name":"t\u00f6\u00f6leht","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}