{"id":421,"count":9,"description":"","link":"https:\/\/ptoshaft.supplies\/et\/tag\/pto-gearbox-for-sale\/","name":"pto gearbox for sale","slug":"pto-gearbox-for-sale","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ptoshaft.supplies\/et\/wp-json\/wp\/v2\/tags\/421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptoshaft.supplies\/et\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ptoshaft.supplies\/et\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ptoshaft.supplies\/et\/wp-json\/wp\/v2\/posts?tags=421"}],"curies":[{"name":"t\u00f6\u00f6leht","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}