{"id":4556,"count":1,"description":"","link":"https:\/\/ptoshaft.supplies\/et\/tag\/lead-screw\/","name":"lead screw","slug":"lead-screw","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ptoshaft.supplies\/et\/wp-json\/wp\/v2\/tags\/4556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptoshaft.supplies\/et\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ptoshaft.supplies\/et\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ptoshaft.supplies\/et\/wp-json\/wp\/v2\/posts?tags=4556"}],"curies":[{"name":"t\u00f6\u00f6leht","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}