{"id":1422,"count":1,"description":"","link":"https:\/\/ptoshaft.supplies\/fi\/tag\/windmill-farm\/","name":"windmill farm","slug":"windmill-farm","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ptoshaft.supplies\/fi\/wp-json\/wp\/v2\/tags\/1422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptoshaft.supplies\/fi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ptoshaft.supplies\/fi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ptoshaft.supplies\/fi\/wp-json\/wp\/v2\/posts?tags=1422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}