{"id":1932,"count":1,"description":"","link":"https:\/\/ptoshaft.supplies\/fi\/tag\/pitch-roller-price-in-india\/","name":"Pitch Roller Price In India","slug":"pitch-roller-price-in-india","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ptoshaft.supplies\/fi\/wp-json\/wp\/v2\/tags\/1932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptoshaft.supplies\/fi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ptoshaft.supplies\/fi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ptoshaft.supplies\/fi\/wp-json\/wp\/v2\/posts?tags=1932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}