{"id":2009,"count":2,"description":"","link":"https:\/\/ptoshaft.supplies\/fi\/tag\/belt-idler\/","name":"belt idler","slug":"belt-idler","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ptoshaft.supplies\/fi\/wp-json\/wp\/v2\/tags\/2009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptoshaft.supplies\/fi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ptoshaft.supplies\/fi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ptoshaft.supplies\/fi\/wp-json\/wp\/v2\/posts?tags=2009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}