{"id":4087,"count":1,"description":"","link":"https:\/\/ptoshaft.supplies\/it\/tag\/idler-pulley-tensioner\/","name":"idler pulley tensioner","slug":"idler-pulley-tensioner","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ptoshaft.supplies\/it\/wp-json\/wp\/v2\/tags\/4087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptoshaft.supplies\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ptoshaft.supplies\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ptoshaft.supplies\/it\/wp-json\/wp\/v2\/posts?tags=4087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}