{"id":3906,"count":1,"description":"","link":"https:\/\/ptoshaft.supplies\/th\/tag\/pto-shaft-for-sale-canada\/","name":"pto shaft for sale canada","slug":"pto-shaft-for-sale-canada","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ptoshaft.supplies\/th\/wp-json\/wp\/v2\/tags\/3906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptoshaft.supplies\/th\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ptoshaft.supplies\/th\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ptoshaft.supplies\/th\/wp-json\/wp\/v2\/posts?tags=3906"}],"curies":[{"name":"\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39\u0e1e\u0e35","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}