{"id":2361,"count":1,"description":"","link":"https:\/\/ptoshaft.supplies\/tr\/tag\/35-roller-chain-pitch-china\/","name":"35 Roller Chain Pitch China","slug":"35-roller-chain-pitch-china","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ptoshaft.supplies\/tr\/wp-json\/wp\/v2\/tags\/2361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptoshaft.supplies\/tr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ptoshaft.supplies\/tr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ptoshaft.supplies\/tr\/wp-json\/wp\/v2\/posts?tags=2361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}