{"id":1490,"count":3,"description":"","link":"https:\/\/ptoshaft.supplies\/zh\/tag\/chain-conveyor-belt\/","name":"chain conveyor belt","slug":"chain-conveyor-belt","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ptoshaft.supplies\/zh\/wp-json\/wp\/v2\/tags\/1490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptoshaft.supplies\/zh\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ptoshaft.supplies\/zh\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ptoshaft.supplies\/zh\/wp-json\/wp\/v2\/posts?tags=1490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}