{"id":268,"count":5,"description":"","link":"https:\/\/ptoshaft.supplies\/zh\/tag\/chain-drive-conveyor-china\/","name":"Chain Drive Conveyor China","slug":"chain-drive-conveyor-china","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ptoshaft.supplies\/zh\/wp-json\/wp\/v2\/tags\/268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptoshaft.supplies\/zh\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ptoshaft.supplies\/zh\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ptoshaft.supplies\/zh\/wp-json\/wp\/v2\/posts?tags=268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}