{"id":337,"count":3,"description":"","link":"https:\/\/ptoshaft.supplies\/zh\/tag\/roller-conveyor-chain-drive-china\/","name":"Roller Conveyor Chain Drive China","slug":"roller-conveyor-chain-drive-china","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ptoshaft.supplies\/zh\/wp-json\/wp\/v2\/tags\/337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptoshaft.supplies\/zh\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ptoshaft.supplies\/zh\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ptoshaft.supplies\/zh\/wp-json\/wp\/v2\/posts?tags=337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}